{"id":1,"date":"2020-03-09T09:52:55","date_gmt":"2020-03-09T08:52:55","guid":{"rendered":"https:\/\/www.die-kronenwerkstatt.de\/?p=1"},"modified":"2020-03-09T17:36:22","modified_gmt":"2020-03-09T16:36:22","slug":"hallo-welt","status":"publish","type":"post","link":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/hallo-welt\/","title":{"rendered":"hallo Leute"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Willkommen bei WordPress. Dies ist dein erster Beitrag. Bearbeite oder l\u00f6sche ihn und beginne mit dem Schreiben!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen bei WordPress. Dies ist dein erster Beitrag. Bearbeite oder l\u00f6sche ihn und beginne mit dem Schreiben!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"_links":{"self":[{"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":1,"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":67,"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions\/67"}],"wp:attachment":[{"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-kronenwerkstatt.de\/index.php\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}